{"id":1402,"date":"2023-10-13T18:51:04","date_gmt":"2023-10-13T16:51:04","guid":{"rendered":"https:\/\/mindef.gov.cm\/armee-de-l-air\/installation-des-nouveaux-responsables-a-lemaa-3\/"},"modified":"2023-10-23T17:59:49","modified_gmt":"2023-10-23T15:59:49","slug":"installation-des-nouveaux-responsables-a-lemaa-3","status":"publish","type":"post","link":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/","title":{"rendered":"INSTALLATION OF NEW MANAGERS AT EMAA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[47,48],"class_list":["post-1402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-actualites-en","tag-banniere-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INSTALLATION OF NEW MANAGERS AT EMAA - Arm\u00e9e De L&#039;Air<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INSTALLATION OF NEW MANAGERS AT EMAA - Arm\u00e9e De L&#039;Air\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Arm\u00e9e De L&#039;Air\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T16:51:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T15:59:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ricaldorichard237@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ricaldorichard237@gmail.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\"},\"author\":{\"name\":\"ricaldorichard237@gmail.com\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/person\/c7c5e12cdabfea449884eaa288241182\"},\"headline\":\"INSTALLATION OF NEW MANAGERS AT EMAA\",\"datePublished\":\"2023-10-13T16:51:04+00:00\",\"dateModified\":\"2023-10-23T15:59:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg\",\"keywords\":[\"Actualit\u00e9s\",\"banniere\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\",\"name\":\"INSTALLATION OF NEW MANAGERS AT EMAA - Arm\u00e9e De L&#039;Air\",\"isPartOf\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg\",\"datePublished\":\"2023-10-13T16:51:04+00:00\",\"dateModified\":\"2023-10-23T15:59:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg\",\"contentUrl\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg\",\"width\":2560,\"height\":1696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INSTALLATION OF NEW MANAGERS AT EMAA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#website\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/\",\"name\":\"Arm\u00e9e De L&#039;Air\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#organization\",\"name\":\"Arm\u00e9e De L&#039;Air\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png\",\"contentUrl\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png\",\"width\":2126,\"height\":478,\"caption\":\"Arm\u00e9e De L&#039;Air\"},\"image\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/person\/c7c5e12cdabfea449884eaa288241182\",\"name\":\"ricaldorichard237@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfa05125461486526b4e04bb167e98d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfa05125461486526b4e04bb167e98d2?s=96&d=mm&r=g\",\"caption\":\"ricaldorichard237@gmail.com\"},\"sameAs\":[\"https:\/\/mindef.gov.cm\"],\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/author\/ricaldorichard237gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INSTALLATION OF NEW MANAGERS AT EMAA - Arm\u00e9e De L&#039;Air","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/","og_locale":"en_US","og_type":"article","og_title":"INSTALLATION OF NEW MANAGERS AT EMAA - Arm\u00e9e De L&#039;Air","og_url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/","og_site_name":"Arm\u00e9e De L&#039;Air","article_published_time":"2023-10-13T16:51:04+00:00","article_modified_time":"2023-10-23T15:59:49+00:00","og_image":[{"width":2560,"height":1696,"url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg","type":"image\/jpeg"}],"author":"ricaldorichard237@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ricaldorichard237@gmail.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#article","isPartOf":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/"},"author":{"name":"ricaldorichard237@gmail.com","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/person\/c7c5e12cdabfea449884eaa288241182"},"headline":"INSTALLATION OF NEW MANAGERS AT EMAA","datePublished":"2023-10-13T16:51:04+00:00","dateModified":"2023-10-23T15:59:49+00:00","mainEntityOfPage":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#organization"},"image":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg","keywords":["Actualit\u00e9s","banniere"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/","name":"INSTALLATION OF NEW MANAGERS AT EMAA - Arm\u00e9e De L&#039;Air","isPartOf":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage"},"image":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg","datePublished":"2023-10-13T16:51:04+00:00","dateModified":"2023-10-23T15:59:49+00:00","breadcrumb":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#primaryimage","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg","contentUrl":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg","width":2560,"height":1696},{"@type":"BreadcrumbList","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/installation-des-nouveaux-responsables-a-lemaa-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/"},{"@type":"ListItem","position":2,"name":"INSTALLATION OF NEW MANAGERS AT EMAA"}]},{"@type":"WebSite","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#website","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/","name":"Arm\u00e9e De L&#039;Air","description":"","publisher":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#organization","name":"Arm\u00e9e De L&#039;Air","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png","contentUrl":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png","width":2126,"height":478,"caption":"Arm\u00e9e De L&#039;Air"},"image":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/person\/c7c5e12cdabfea449884eaa288241182","name":"ricaldorichard237@gmail.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfa05125461486526b4e04bb167e98d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfa05125461486526b4e04bb167e98d2?s=96&d=mm&r=g","caption":"ricaldorichard237@gmail.com"},"sameAs":["https:\/\/mindef.gov.cm"],"url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/author\/ricaldorichard237gmail-com\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg",2560,1696,false],"landscape":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg",2560,1696,false],"portraits":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg",2560,1696,false],"thumbnail":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-150x150.jpg",150,150,true],"medium":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-300x199.jpg",300,199,true],"large":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-1024x678.jpg",800,530,true],"1536x1536":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-1536x1017.jpg",1536,1017,true],"2048x2048":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-2048x1356.jpg",2048,1356,true],"htmega_size_585x295":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-585x295.jpg",585,295,true],"htmega_size_1170x536":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-1170x536.jpg",1170,536,true],"htmega_size_396x360":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-396x360.jpg",396,360,true],"rt_custom":["https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/10\/installation-2-scaled.jpg",2560,1696,false]},"rttpg_author":{"display_name":"ricaldorichard237@gmail.com","author_link":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/author\/ricaldorichard237gmail-com\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/category\/non-classifiee\/\" rel=\"category tag\">Non classifi\u00e9(e)<\/a>","rttpg_excerpt":null,"_links":{"self":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/posts\/1402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/comments?post=1402"}],"version-history":[{"count":0,"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/posts\/1402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/media\/1350"}],"wp:attachment":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/media?parent=1402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/categories?post=1402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/en\/wp-json\/wp\/v2\/tags?post=1402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}