{"id":37,"count":3,"description":"","link":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/","name":"Formation","slug":"formation","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formation Archives - Arm\u00e9e De L&#039;Air<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formation Archives - Arm\u00e9e De L&#039;Air\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/\" \/>\n<meta property=\"og:site_name\" content=\"Arm\u00e9e De L&#039;Air\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/\",\"name\":\"Formation Archives - Arm\u00e9e De L&#039;Air\",\"isPartOf\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/#website\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/\",\"name\":\"Arm\u00e9e De L&#039;Air\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/#organization\",\"name\":\"Arm\u00e9e De L&#039;Air\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png\",\"contentUrl\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png\",\"width\":2126,\"height\":478,\"caption\":\"Arm\u00e9e De L&#039;Air\"},\"image\":{\"@id\":\"https:\/\/mindef.gov.cm\/armee-de-l-air\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formation Archives - Arm\u00e9e De L&#039;Air","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/","og_locale":"fr_FR","og_type":"article","og_title":"Formation Archives - Arm\u00e9e De L&#039;Air","og_url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/","og_site_name":"Arm\u00e9e De L&#039;Air","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/","name":"Formation Archives - Arm\u00e9e De L&#039;Air","isPartOf":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/#website"},"breadcrumb":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/category\/formation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mindef.gov.cm\/armee-de-l-air\/accueil\/"},{"@type":"ListItem","position":2,"name":"Formation"}]},{"@type":"WebSite","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/#website","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/","name":"Arm\u00e9e De L&#039;Air","description":"","publisher":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mindef.gov.cm\/armee-de-l-air\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/#organization","name":"Arm\u00e9e De L&#039;Air","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/#\/schema\/logo\/image\/","url":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png","contentUrl":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-content\/uploads\/sites\/6\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png","width":2126,"height":478,"caption":"Arm\u00e9e De L&#039;Air"},"image":{"@id":"https:\/\/mindef.gov.cm\/armee-de-l-air\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-json\/wp\/v2\/categories\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mindef.gov.cm\/armee-de-l-air\/wp-json\/wp\/v2\/posts?categories=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}