{"id":80,"count":4,"description":"","link":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/","name":"Gendarmerie de proximit\u00e9","slug":"gendarmerie-de-proximite","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gendarmerie de proximit\u00e9 Archives - Gendarmerie Nationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gendarmerie de proximit\u00e9 Archives - Gendarmerie Nationale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/\" \/>\n<meta property=\"og:site_name\" content=\"Gendarmerie Nationale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/\",\"url\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/\",\"name\":\"Gendarmerie de proximit\u00e9 Archives - Gendarmerie Nationale\",\"isPartOf\":{\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gendarmerie de proximit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#website\",\"url\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/\",\"name\":\"Gendarmerie Nationale\",\"description\":\"Site Web GENDAMERIE\",\"publisher\":{\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#organization\",\"name\":\"Gendarmerie Nationale\",\"url\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-content\/uploads\/sites\/2\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png\",\"contentUrl\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-content\/uploads\/sites\/2\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png\",\"width\":2126,\"height\":478,\"caption\":\"Gendarmerie Nationale\"},\"image\":{\"@id\":\"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gendarmerie de proximit\u00e9 Archives - Gendarmerie Nationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/","og_locale":"fr_FR","og_type":"article","og_title":"Gendarmerie de proximit\u00e9 Archives - Gendarmerie Nationale","og_url":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/","og_site_name":"Gendarmerie Nationale","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/","url":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/","name":"Gendarmerie de proximit\u00e9 Archives - Gendarmerie Nationale","isPartOf":{"@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#website"},"breadcrumb":{"@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/tag\/gendarmerie-de-proximite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/"},{"@type":"ListItem","position":2,"name":"Gendarmerie de proximit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#website","url":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/","name":"Gendarmerie Nationale","description":"Site Web GENDAMERIE","publisher":{"@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#organization","name":"Gendarmerie Nationale","url":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#\/schema\/logo\/image\/","url":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-content\/uploads\/sites\/2\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png","contentUrl":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-content\/uploads\/sites\/2\/2023\/07\/LOGO-MINDEF-PNG-FRANCAIS.png","width":2126,"height":478,"caption":"Gendarmerie Nationale"},"image":{"@id":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-json\/wp\/v2\/tags\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mindef.gov.cm\/gendarmerie-nationale\/wp-json\/wp\/v2\/posts?tags=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}